{"id":990,"date":"2018-03-10T11:43:20","date_gmt":"2018-03-10T10:43:20","guid":{"rendered":"http:\/\/www.angoloavventurabari.it\/?p=990"},"modified":"2018-03-10T12:08:16","modified_gmt":"2018-03-10T11:08:16","slug":"21-marzo-ore-19-30-il-cammino-real-alla-scoperta-degli-incas-del-peru-e-bolivia","status":"publish","type":"post","link":"https:\/\/www.angoloavventurabari.it\/index.php\/2018\/03\/10\/21-marzo-ore-19-30-il-cammino-real-alla-scoperta-degli-incas-del-peru-e-bolivia\/","title":{"rendered":"21 Marzo ore 19.30- IL CAMMINO REAL: Alla scoperta degli Incas del Peru e Bolivia"},"content":{"rendered":"<p><a href=\"https:\/\/i0.wp.com\/www.angoloavventurabari.it\/wp-content\/uploads\/2018\/03\/Nuova_21Marzo.jpg\" rel=\"attachment wp-att-1000\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" data-attachment-id=\"1000\" data-permalink=\"https:\/\/www.angoloavventurabari.it\/index.php\/2018\/03\/10\/21-marzo-ore-19-30-il-cammino-real-alla-scoperta-degli-incas-del-peru-e-bolivia\/nuova_21marzo\/\" data-orig-file=\"https:\/\/i0.wp.com\/www.angoloavventurabari.it\/wp-content\/uploads\/2018\/03\/Nuova_21Marzo.jpg?fit=837%2C747&amp;ssl=1\" data-orig-size=\"837,747\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"Nuova_21Marzo\" data-image-description=\"\" data-image-caption=\"\" data-medium-file=\"https:\/\/i0.wp.com\/www.angoloavventurabari.it\/wp-content\/uploads\/2018\/03\/Nuova_21Marzo.jpg?fit=300%2C268&amp;ssl=1\" data-large-file=\"https:\/\/i0.wp.com\/www.angoloavventurabari.it\/wp-content\/uploads\/2018\/03\/Nuova_21Marzo.jpg?fit=590%2C527&amp;ssl=1\" class=\"size-medium wp-image-1000 alignleft\" src=\"https:\/\/i0.wp.com\/www.angoloavventurabari.it\/wp-content\/uploads\/2018\/03\/Nuova_21Marzo-300x268.jpg?resize=300%2C268\" alt=\"Nuova_21Marzo\" width=\"300\" height=\"268\" srcset=\"https:\/\/i0.wp.com\/www.angoloavventurabari.it\/wp-content\/uploads\/2018\/03\/Nuova_21Marzo.jpg?resize=300%2C268&amp;ssl=1 300w, https:\/\/i0.wp.com\/www.angoloavventurabari.it\/wp-content\/uploads\/2018\/03\/Nuova_21Marzo.jpg?w=837&amp;ssl=1 837w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a><\/p>\n<p>L\u2019Angolo Avventura di Bari e\u2019 lieta di invitarvi ad un nuovo racconto di viaggio di una splendida coppia di viaggiatori :<br \/>\nGIUSEPPE FORNELLI e LUCIA ALTOBELLO<br \/>\namici di vecchia data dell&#8217;Angolo di Bari.<\/p>\n<p>MERCOLEDI 21 MARZO ore 19.30<br \/>\npresso Cineporto di Bari, Fiera del Levante padiglione 180, sede Apulia Film Commission, Lungomare Starita, 1<\/p>\n<p>Racconteranno del Per\u00f9 e Bolivia, l\u2019altopiano andino, culla di antiche civilt\u00e0 la cui origine ancora oggi \u00e8 avvolta nel mistero, nello scenario impareggiabile delle innevate e scintillanti vette andine. Si andr\u00e0 dalle grandi Cordigliere del nord, alla grandiosit\u00e0 della Cordelliera Real Boliviana, alle distese desertiche; dagli immensi altopiani, all\u2019unicit\u00e0 del Lago Titicac<span class=\"text_exposed_show\">a, il pi\u00f9 alto del mondo, ai Salares e alle lagune boliviane; dagli spettacolari siti archeologici delle tante civilt\u00e0 susseguitesi nel corso della Storia. Particolari anche i centri abitati: la convulsa e contraddittoria Lima, la meravigliosa Cusco, l&#8217;affascinante Arequipa e La Paz con i suoi 4000 m via via fino alle cittadine, i paesini, i villaggi, i minuscoli gruppi di case nei luoghi pi\u00f9 sperduti E poi c&#8217;\u00e8 la gente: i campesinos delle zone rurali, che seguono i ritmi del sole lavorando sodo all&#8217;aperto dall&#8217;alba al tramonto e la folla di venditori e acquirenti degli onnipresenti e variopinti mercati. Per tutti questi motivi, il Per\u00f9 e la Bolivia rappresentano i due paesi pi\u00f9 colorati che un viaggiatore possa visitare.<\/span><\/p>\n<p>Vi aspettiamo!<br \/>\n(ingresso e parcheggio GRATUITO lato EATALY)<\/p>\n","protected":false},"excerpt":{"rendered":"<p>L\u2019Angolo Avventura di Bari e\u2019 lieta di invitarvi ad un nuovo racconto di viaggio di una splendida coppia di viaggiatori : GIUSEPPE FORNELLI e LUCIA ALTOBELLO amici di vecchia data dell&#8217;Angolo di Bari. MERCOLEDI 21 MARZO ore 19.30 presso Cineporto&#8230; <a class=\"read-more-button\" href=\"https:\/\/www.angoloavventurabari.it\/index.php\/2018\/03\/10\/21-marzo-ore-19-30-il-cammino-real-alla-scoperta-degli-incas-del-peru-e-bolivia\/\">(LEGGI TUTTO)<\/a><\/p>\n","protected":false},"author":1,"featured_media":1000,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"jetpack_post_was_ever_published":false,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[4],"tags":[],"class_list":["post-990","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-incontri"],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/i0.wp.com\/www.angoloavventurabari.it\/wp-content\/uploads\/2018\/03\/Nuova_21Marzo.jpg?fit=837%2C747&ssl=1","jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/p7nIYh-fY","jetpack-related-posts":[],"_links":{"self":[{"href":"https:\/\/www.angoloavventurabari.it\/index.php\/wp-json\/wp\/v2\/posts\/990","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.angoloavventurabari.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.angoloavventurabari.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.angoloavventurabari.it\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.angoloavventurabari.it\/index.php\/wp-json\/wp\/v2\/comments?post=990"}],"version-history":[{"count":4,"href":"https:\/\/www.angoloavventurabari.it\/index.php\/wp-json\/wp\/v2\/posts\/990\/revisions"}],"predecessor-version":[{"id":1001,"href":"https:\/\/www.angoloavventurabari.it\/index.php\/wp-json\/wp\/v2\/posts\/990\/revisions\/1001"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.angoloavventurabari.it\/index.php\/wp-json\/wp\/v2\/media\/1000"}],"wp:attachment":[{"href":"https:\/\/www.angoloavventurabari.it\/index.php\/wp-json\/wp\/v2\/media?parent=990"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.angoloavventurabari.it\/index.php\/wp-json\/wp\/v2\/categories?post=990"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.angoloavventurabari.it\/index.php\/wp-json\/wp\/v2\/tags?post=990"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}